{"id":8348,"date":"2022-12-09T11:13:06","date_gmt":"2022-12-09T11:13:06","guid":{"rendered":"https:\/\/winesfromaragon.com\/?post_type=uvas&#038;p=8348"},"modified":"2023-01-12T08:30:55","modified_gmt":"2023-01-12T08:30:55","slug":"senorio-de-san-vicen","status":"publish","type":"uvas","link":"https:\/\/winesfromaragon.com\/en\/vinos\/senorio-de-san-vicen\/","title":{"rendered":"Se\u00f1or\u00edo de San Vic\u00e9n"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":8349,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false},"vinos-do":[92],"vinos-category":[98],"class_list":["post-8348","uvas","type-uvas","status-publish","format-standard","has-post-thumbnail","hentry","vinos-do-calatayud-en","vinos-category-tinto-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/uvas\/8348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/uvas"}],"about":[{"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/types\/uvas"}],"replies":[{"embeddable":true,"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/comments?post=8348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/media\/8349"}],"wp:attachment":[{"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/media?parent=8348"}],"wp:term":[{"taxonomy":"vinos-do","embeddable":true,"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/vinos-do?post=8348"},{"taxonomy":"vinos-category","embeddable":true,"href":"https:\/\/winesfromaragon.com\/en\/wp-json\/wp\/v2\/vinos-category?post=8348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}